{"id":11046,"date":"2021-09-11T07:00:11","date_gmt":"2021-09-11T10:00:11","guid":{"rendered":"https:\/\/chelso.com.br\/site\/?p=11046"},"modified":"2021-09-10T18:43:59","modified_gmt":"2021-09-10T21:43:59","slug":"aquecimento-ou-alongamento","status":"publish","type":"post","link":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/","title":{"rendered":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Fala galera, tudo <\/span><i><span style=\"font-weight: 400;\">arriba<\/span><\/i><span style=\"font-weight: 400;\"> por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &#8220;aquecimento ou alongamento&#8221;, e mostrar qual momento de usar cada um.<\/span><\/p>\n<h2>Aquecimento ou alongamento?<\/h2>\n<p><span style=\"font-weight: 400;\">Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a atividade alvo (seja corrida, ciclismo, muscula\u00e7\u00e3o). Como j\u00e1 trouxe aqui existem alguns aquecimentos espec\u00edficos para os corredores; e muito mais do que caminhar na esteira eles podem ser feitos de outras formas: por exemplo, na muscula\u00e7\u00e3o voc\u00ea pode aquecer com o pr\u00f3prio exerc\u00edcio, por\u00e9m com cargas menores. Na corrida voc\u00ea pode utilizar os educativos para preparar seu corpo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O aquecimento \u00e9 uma forma de aumentar a frequ\u00eancia card\u00edaca, a circula\u00e7\u00e3o sangu\u00ednea nos m\u00fasculos\/tend\u00f5es e lubrificar as articula\u00e7\u00f5es prevenindo as les\u00f5es.<\/span><\/p>\n<p><a href=\"https:\/\/chelso.com.br\/site\/provas-presenciais\/\">+Confira nosso calend\u00e1rio de provas presenciais<\/a><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 o ALONGAMENTO auxilia na flexibilidade e ativa a circula\u00e7\u00e3o do corpo. Ele pode ser ativo (quando o individuo realiza sozinho) ou passivo (quando h\u00e1 uma ajuda externa \u2013 professor \u2013 no movimento). Esse tipo de exerc\u00edcio ajuda no aumento da amplitude de movimento (ADM) essencial para, tamb\u00e9m, evitar les\u00f5es e melhorar na performance. Mas a quest\u00e3o \u00e9 quando us\u00e1-los?\u00a0<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-11047\" src=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/09\/Aquecimento-ou-alongamento-1024x614.jpg\" alt=\"Aquecimento ou alongamento \" width=\"788\" height=\"472\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Alguns estudos mostram que alongamentos vigorosos antes do treino de for\u00e7a podem diminuir o desempenho; e que alongamentos excessivos ap\u00f3s a sess\u00e3o de treino podem gerar algumas les\u00f5es pelo estiramento muscular (lembrando que o treino resistido promove um encurtamento das fibras). <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, a minha sugest\u00e3o \u00e9 que ap\u00f3s o treino voc\u00ea realize alongamentos b\u00e1sicos, abrangendo todos os m\u00fasculos trabalhados na sess\u00e3o, sem ultrapassar 20\u201d.\u00a0 Assim promove-se um relaxamento sem gerar grande demanda de sobrecarga \u2013 cuidado para n\u00e3o confundir alongamento com treino de flexibilidade! (assunto para uma pr\u00f3xima ok?)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Agora que voc\u00ea j\u00e1 sabe, que tal conversar com seu treinador e verificar quais op\u00e7\u00f5es se enquadram melhor na sua periodiza\u00e7\u00e3o? Precisando, me chama l\u00e1 no <a href=\"https:\/\/www.instagram.com\/nessa_haaspersonal\/\">insta!<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &#8220;aquecimento ou alongamento&#8221;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[89,31],"tags":[727,725,735,41,36,37,127],"class_list":["post-11046","post","type-post","status-publish","format-standard","category-dicas","category-treinos","tag-alongamento","tag-aquecimento","tag-chelso","tag-chelso-sports","tag-corrida","tag-corrida-de-rua","tag-treinos"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &quot;aquecimento ou alongamento&quot;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chelso\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports\" \/>\n\t\t<meta property=\"og:description\" content=\"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &quot;aquecimento ou alongamento&quot;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-11T10:00:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-10T21:43:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &quot;aquecimento ou alongamento&quot;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#blogposting\",\"name\":\"Aquecimento ou alongamento: voc\\u00ea sabe em qual momento us\\u00e1-los? - Portal Chelso Sports\",\"headline\":\"Aquecimento ou alongamento: voc\\u00ea sabe em qual momento us\\u00e1-los?\",\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Aquecimento-ou-alongamento.jpg\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#articleImage\"},\"datePublished\":\"2021-09-11T07:00:11-03:00\",\"dateModified\":\"2021-09-10T18:43:59-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#webpage\"},\"articleSection\":\"Dicas, Treinos, alongamento, Aquecimento, Chelso, chelso sports, corrida, corrida de rua, Treinos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/treinos\\\/#listItem\",\"name\":\"Treinos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/treinos\\\/#listItem\",\"position\":2,\"name\":\"Treinos\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/treinos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#listItem\",\"name\":\"Aquecimento ou alongamento: voc\\u00ea sabe em qual momento us\\u00e1-los?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#listItem\",\"position\":3,\"name\":\"Aquecimento ou alongamento: voc\\u00ea sabe em qual momento us\\u00e1-los?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/treinos\\\/#listItem\",\"name\":\"Treinos\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/\",\"name\":\"Chelso\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#authorImage\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Perfil20192-150x149.png\",\"width\":96,\"height\":96,\"caption\":\"Chelso\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#webpage\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/\",\"name\":\"Aquecimento ou alongamento: voc\\u00ea sabe em qual momento us\\u00e1-los? - Portal Chelso Sports\",\"description\":\"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \\u00e9 para esclarecer algumas d\\u00favidas que ainda restam sobre \\\"aquecimento ou alongamento\\\", e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\\u00e7ar falando sobre o AQUECIMENTO: como o pr\\u00f3prio nome j\\u00e1 diz ele serve para preparar nosso corpo para a\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/aquecimento-ou-alongamento\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"datePublished\":\"2021-09-11T07:00:11-03:00\",\"dateModified\":\"2021-09-10T18:43:59-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports","description":"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre \"aquecimento ou alongamento\", e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a","canonical_url":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#blogposting","name":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports","headline":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?","author":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/09\/Aquecimento-ou-alongamento.jpg","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#articleImage"},"datePublished":"2021-09-11T07:00:11-03:00","dateModified":"2021-09-10T18:43:59-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#webpage"},"isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#webpage"},"articleSection":"Dicas, Treinos, alongamento, Aquecimento, Chelso, chelso sports, corrida, corrida de rua, Treinos"},{"@type":"BreadcrumbList","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","position":1,"name":"Home","item":"https:\/\/chelso.com.br\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/treinos\/#listItem","name":"Treinos"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/treinos\/#listItem","position":2,"name":"Treinos","item":"https:\/\/chelso.com.br\/site\/category\/treinos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#listItem","name":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#listItem","position":3,"name":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?","previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/treinos\/#listItem","name":"Treinos"}}]},{"@type":"Organization","@id":"https:\/\/chelso.com.br\/site\/#organization","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","url":"https:\/\/chelso.com.br\/site\/"},{"@type":"Person","@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author","url":"https:\/\/chelso.com.br\/site\/author\/maryblog\/","name":"Chelso","image":{"@type":"ImageObject","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#authorImage","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2025\/04\/Perfil20192-150x149.png","width":96,"height":96,"caption":"Chelso"}},{"@type":"WebPage","@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#webpage","url":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/","name":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports","description":"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre \"aquecimento ou alongamento\", e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/#breadcrumblist"},"author":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"creator":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"datePublished":"2021-09-11T07:00:11-03:00","dateModified":"2021-09-10T18:43:59-03:00"},{"@type":"WebSite","@id":"https:\/\/chelso.com.br\/site\/#website","url":"https:\/\/chelso.com.br\/site\/","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon","og:type":"article","og:title":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports","og:description":"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &quot;aquecimento ou alongamento&quot;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a","og:url":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/","article:published_time":"2021-09-11T10:00:11+00:00","article:modified_time":"2021-09-10T21:43:59+00:00","twitter:card":"summary_large_image","twitter:title":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los? - Portal Chelso Sports","twitter:description":"Fala galera, tudo arriba por ai?? Espero que sim! Hoje nosso papo \u00e9 para esclarecer algumas d\u00favidas que ainda restam sobre &quot;aquecimento ou alongamento&quot;, e mostrar qual momento de usar cada um. Aquecimento ou alongamento? Vamos come\u00e7ar falando sobre o AQUECIMENTO: como o pr\u00f3prio nome j\u00e1 diz ele serve para preparar nosso corpo para a"},"aioseo_meta_data":{"post_id":"11046","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-06 01:11:48","updated":"2025-07-02 18:24:51","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\/category\/treinos\/\" title=\"Treinos\">Treinos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chelso.com.br\/site"},{"label":"Treinos","link":"https:\/\/chelso.com.br\/site\/category\/treinos\/"},{"label":"Aquecimento ou alongamento: voc\u00ea sabe em qual momento us\u00e1-los?","link":"https:\/\/chelso.com.br\/site\/aquecimento-ou-alongamento\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/11046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/comments?post=11046"}],"version-history":[{"count":1,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/11046\/revisions"}],"predecessor-version":[{"id":11049,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/11046\/revisions\/11049"}],"wp:attachment":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/media?parent=11046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/categories?post=11046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/tags?post=11046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}