{"id":20425,"date":"2024-06-20T17:18:52","date_gmt":"2024-06-20T20:18:52","guid":{"rendered":"https:\/\/chelso.com.br\/site\/?p=20425"},"modified":"2024-06-20T17:18:52","modified_gmt":"2024-06-20T20:18:52","slug":"asics-gel-nimbus-26-tr","status":"publish","type":"post","link":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/","title":{"rendered":"Asics GEL-NIMBUS\u2122 26 TR"},"content":{"rendered":"<p><strong>Asics GEL-NIMBUS\u2122 26 TR! <\/strong>A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor.<\/p>\n<p>Com um cabedal confeccionado em malha macia e 75% de materiais reciclados, o Nimbus 26 TR envolve os p\u00e9s com conforto e responsabilidade ambiental. A ventila\u00e7\u00e3o avan\u00e7ada e o suporte da lingueta e colarinho em knit garantem que cada passo seja t\u00e3o refrescante quanto seguro.<\/p>\n<p><a href=\"https:\/\/chelso.com.br\/site\/provas-presenciais\/\">Saiba mais sobre o nosso calend\u00e1rio de provas presenciais<\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-20427\" src=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26.jpg\" alt=\"Asics GEL-NIMBUS\u2122 26 TR\" width=\"768\" height=\"459\" srcset=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26.jpg 768w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26-300x179.jpg 300w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26-150x90.jpg 150w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26-450x269.jpg 450w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/p>\n<h2><strong>Asics GEL-NIMBUS\u2122 26 TR<\/strong><\/h2>\n<p>A inova\u00e7\u00e3o continua na entressola com a tecnologia FF BLAST\u2122 PLUS ECO, que oferece um amortecimento leve e macio, reduzindo o impacto ambiental sem comprometer a performance. A sola HYBRID ASICSGRIP\u2122 combina ader\u00eancia excepcional e durabilidade, tornando cada terreno uma nova conquista.<\/p>\n<p>Para os corredores noturnos, os detalhes reflexivos asseguram visibilidade e seguran\u00e7a, enquanto a palmilha OrthoLite\u2122 X-55 adiciona conforto extra e controle de umidade. E com o processo de tingimento em solu\u00e7\u00e3o, a ASICS reduz significativamente o uso de \u00e1gua e emiss\u00f5es de carbono, reafirmando seu compromisso com o planeta.<\/p>\n<p>O GEL-NIMBUS\u2122 26 TR j\u00e1 est\u00e1 dispon\u00edvel nas lojas e e-commerce da ASICS e nos parceiros especializados, como a Netshoes ou Centauro, pelo pre\u00e7o sugerido de R$ 1.299,99.<\/p>\n<p>GEL-NIMBUS\u2122 26 TR<br \/>\nPeso: 322g | Drop: 8mm<br \/>\nGrade: do 38 ao 44<br \/>\nPre\u00e7o: R$ 1.299,99 |<\/p>\n<p><iframe  id=\"_ytid_26555\"  width=\"788\" height=\"443\"  data-origwidth=\"788\" data-origheight=\"443\" src=\"https:\/\/www.youtube.com\/embed\/xbxRk2MnZCc?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n<h3><b>Siga a Chelso<\/b><\/h3>\n<p>A Chelso Sports est\u00e1 presente no\u00a0<a href=\"https:\/\/www.youtube.com\/@ChelsoSports\">YouTube<\/a>! Por isso, convidamos voc\u00ea a se inscrever em nosso canal, deixar seus coment\u00e1rios e ficar por dentro de todas as novidades do mundo dos esportes. Ultrapassamos a marca de 4 mil inscritos e, como nossa nova meta \u00e9 chegar aos 5 mil, n\u00e3o deixe de acompanhar nossos v\u00eddeos exclusivos.<\/p>\n<p>Al\u00e9m disso, n\u00e3o para por a\u00ed! Se voc\u00ea quer ter acesso a todas as informa\u00e7\u00f5es sobre nosso calend\u00e1rio de provas e dicas de treinamento, \u00e9 s\u00f3 seguir a Chelso Sports no\u00a0<a href=\"https:\/\/www.instagram.com\/chelsosports\/\">Instagram<\/a>. Fique por dentro de curiosidades e novidades sobre os esportes outdoor. Ent\u00e3o, n\u00e3o perca tempo e nos acompanhe agora mesmo nas redes sociais!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em<\/p>\n","protected":false},"author":21,"featured_media":20426,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[89,30],"tags":[878,4249,735,41,4250],"class_list":["post-20425","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dicas","category-noticias","tag-asics","tag-asics-gel-nimbus-26-tr","tag-chelso","tag-chelso-sports","tag-gel-nimbus"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chelso\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports\" \/>\n\t\t<meta property=\"og:description\" content=\"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-06-20T20:18:52+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-20T20:18:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#blogposting\",\"name\":\"Asics GEL-NIMBUS\\u2122 26 TR - Portal Chelso Sports\",\"headline\":\"Asics GEL-NIMBUS\\u2122 26 TR\",\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Asics-Gel-Nimbus-26-2.jpg\",\"width\":758,\"height\":472,\"caption\":\"Asics GEL-NIMBUS\\u2122 26 TR\"},\"datePublished\":\"2024-06-20T17:18:52-03:00\",\"dateModified\":\"2024-06-20T17:18:52-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#webpage\"},\"articleSection\":\"Dicas, Not\\u00edcias, Asics, Asics GEL-NIMBUS\\u2122 26 TR, Chelso, chelso sports, GEL-NIMBUS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#listItem\",\"name\":\"Asics GEL-NIMBUS\\u2122 26 TR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#listItem\",\"position\":3,\"name\":\"Asics GEL-NIMBUS\\u2122 26 TR\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/\",\"name\":\"Chelso\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#authorImage\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Perfil20192-150x149.png\",\"width\":96,\"height\":96,\"caption\":\"Chelso\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#webpage\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/\",\"name\":\"Asics GEL-NIMBUS\\u2122 26 TR - Portal Chelso Sports\",\"description\":\"Asics GEL-NIMBUS\\u2122 26 TR! A ASICS acaba de lan\\u00e7ar uma revolu\\u00e7\\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\\u2122 26 TR. Este t\\u00eanis n\\u00e3o \\u00e9 apenas um cal\\u00e7ado, \\u00e9 uma declara\\u00e7\\u00e3o de excel\\u00eancia e sustentabilidade, projetado para corredores que n\\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/maryblog\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Asics-Gel-Nimbus-26-2.jpg\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#mainImage\",\"width\":758,\"height\":472,\"caption\":\"Asics GEL-NIMBUS\\u2122 26 TR\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/asics-gel-nimbus-26-tr\\\/#mainImage\"},\"datePublished\":\"2024-06-20T17:18:52-03:00\",\"dateModified\":\"2024-06-20T17:18:52-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports","description":"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em","canonical_url":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#blogposting","name":"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports","headline":"Asics GEL-NIMBUS\u2122 26 TR","author":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26-2.jpg","width":758,"height":472,"caption":"Asics GEL-NIMBUS\u2122 26 TR"},"datePublished":"2024-06-20T17:18:52-03:00","dateModified":"2024-06-20T17:18:52-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#webpage"},"isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#webpage"},"articleSection":"Dicas, Not\u00edcias, Asics, Asics GEL-NIMBUS\u2122 26 TR, Chelso, chelso sports, GEL-NIMBUS"},{"@type":"BreadcrumbList","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","position":1,"name":"Home","item":"https:\/\/chelso.com.br\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/chelso.com.br\/site\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#listItem","name":"Asics GEL-NIMBUS\u2122 26 TR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#listItem","position":3,"name":"Asics GEL-NIMBUS\u2122 26 TR","previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/chelso.com.br\/site\/#organization","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","url":"https:\/\/chelso.com.br\/site\/"},{"@type":"Person","@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author","url":"https:\/\/chelso.com.br\/site\/author\/maryblog\/","name":"Chelso","image":{"@type":"ImageObject","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#authorImage","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2025\/04\/Perfil20192-150x149.png","width":96,"height":96,"caption":"Chelso"}},{"@type":"WebPage","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#webpage","url":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/","name":"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports","description":"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#breadcrumblist"},"author":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"creator":{"@id":"https:\/\/chelso.com.br\/site\/author\/maryblog\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2024\/06\/Asics-Gel-Nimbus-26-2.jpg","@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#mainImage","width":758,"height":472,"caption":"Asics GEL-NIMBUS\u2122 26 TR"},"primaryImageOfPage":{"@id":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/#mainImage"},"datePublished":"2024-06-20T17:18:52-03:00","dateModified":"2024-06-20T17:18:52-03:00"},{"@type":"WebSite","@id":"https:\/\/chelso.com.br\/site\/#website","url":"https:\/\/chelso.com.br\/site\/","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon","og:type":"article","og:title":"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports","og:description":"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em","og:url":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/","article:published_time":"2024-06-20T20:18:52+00:00","article:modified_time":"2024-06-20T20:18:52+00:00","twitter:card":"summary_large_image","twitter:title":"Asics GEL-NIMBUS\u2122 26 TR - Portal Chelso Sports","twitter:description":"Asics GEL-NIMBUS\u2122 26 TR! A ASICS acaba de lan\u00e7ar uma revolu\u00e7\u00e3o no mundo das corridas de trilhas e montanhas: o GEL-NIMBUS\u2122 26 TR. Este t\u00eanis n\u00e3o \u00e9 apenas um cal\u00e7ado, \u00e9 uma declara\u00e7\u00e3o de excel\u00eancia e sustentabilidade, projetado para corredores que n\u00e3o se contentam com menos do que o melhor. Com um cabedal confeccionado em"},"aioseo_meta_data":{"post_id":"20425","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-06-20 20:18:52","updated":"2025-07-02 19:13:49","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\/category\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAsics GEL-NIMBUS\u2122 26 TR\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chelso.com.br\/site"},{"label":"Not\u00edcias","link":"https:\/\/chelso.com.br\/site\/category\/noticias\/"},{"label":"Asics GEL-NIMBUS\u2122 26 TR","link":"https:\/\/chelso.com.br\/site\/asics-gel-nimbus-26-tr\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/20425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/comments?post=20425"}],"version-history":[{"count":1,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/20425\/revisions"}],"predecessor-version":[{"id":20428,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/20425\/revisions\/20428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/media\/20426"}],"wp:attachment":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/media?parent=20425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/categories?post=20425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/tags?post=20425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}