{"id":7689,"date":"2021-03-19T16:02:09","date_gmt":"2021-03-19T19:02:09","guid":{"rendered":"https:\/\/chelso.com.br\/site\/?p=7689"},"modified":"2021-03-19T16:06:42","modified_gmt":"2021-03-19T19:06:42","slug":"voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras","status":"publish","type":"post","link":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/","title":{"rendered":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda de algu\u00e9m necessitado, em busca de uma sociedade mais justa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A ONU define o voluntariado como \u201c<\/span><i><span style=\"font-weight: 400;\">o jovem ou o adulto que, devido ao seu interesse pessoal e ao seu esp\u00edrito c\u00edvico, dedica parte de seu tempo, sem remunera\u00e7\u00e3o alguma, a diversas formas de atividades, organizadas ou n\u00e3o, de bem-estar social ou outros campos\u201d.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Desta forma, ser um volunt\u00e1rio do projeto <a href=\"https:\/\/www.pernascaipiras.com.br\/\">Pernas Caipiras<\/a> \u00e9 engajar-se numa luta pela valoriza\u00e7\u00e3o das potencialidades e diversidade humana.\u00a0<\/span><span style=\"font-weight: 400;\">Ser volunt\u00e1rio \u00e9 desejar ajudar o pr\u00f3ximo sem fins lucrativos, mas almejando uma sociedade e um mundo melhor.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.chelso.com.br\/site\/provas\/corrida-virtual-pernas-caipiras\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4337\" src=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2020\/11\/PERNAS.jpg\" alt=\"\" width=\"728\" height=\"90\" \/><\/a><\/p>\n<h3><strong>Voc\u00ea deve estar se perguntando, como eu posso AJUDAR o projeto Pernas Caipiras?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Uma das formas mais simples de ajudar \u00e9 sendo um guia volunt\u00e1rio dos nossos triciclos, emprestando suas pernas, cora\u00e7\u00e3o e motiva\u00e7\u00e3o aos conduzidos. <\/span><span style=\"font-weight: 400;\">Aqui, ningu\u00e9m precisa ser atleta de elite para participar, basta que voc\u00ea seja um praticante regular de corrida para participar, j\u00e1 que, durante as provas h\u00e1 um revezamento de condutores, para que ningu\u00e9m se sinta sobrecarregado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para se tornar um condutor \u00e9 muito simples, basta acessar o site <\/span><a href=\"http:\/\/www.pernascaipiras.com.br\"><span style=\"font-weight: 400;\">www.pernascaipiras.com.br<\/span><\/a><span style=\"font-weight: 400;\"> e realizar o seu cadastro como condutor volunt\u00e1rio. Lembramos que preencher corretamente todos os dados solicitados \u00e9 fundamental para a sua seguran\u00e7a e a de todos os envolvidos no processo. Com o cadastro finalizado voc\u00ea j\u00e1 est\u00e1 na nossa lista de condutores e poder\u00e1 ser convocado a qualquer momento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea n\u00e3o \u00e9 um corredor, mas deseja engajar-se nesta a\u00e7\u00e3o volunt\u00e1ria pode auxiliar nas tendas como apoio nesses eventos e em a\u00e7\u00f5es beneficentes em que o Pernas Caipiras estiver presente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, l\u00e1 no nosso site voc\u00ea vai encontrar outras formas interessantes de ajudar o projeto:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Voc\u00ea pode ser um parceiro contribuindo financeiramente para que o Pernas Caipiras continue replicando essas a\u00e7\u00f5es de inclus\u00e3o social. Para fazer sua doa\u00e7\u00e3o \u00e9 f\u00e1cil, basta acessar o site do Pernas Caipiras e escolher a op\u00e7\u00e3o desejada (PIX, transfer\u00eancia banc\u00e1ria, cart\u00e3o de cr\u00e9dito ou QR Code).<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Voc\u00ea pode adquirir nossos produtos (camisetas, copos, adesivos e muitos outros) e toda renda ser\u00e1 revertida em prol ao projeto.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Voc\u00ea pode ser um patrocinador do projeto, divulgando sua marca ou empresa durante as lives que s\u00e3o realizadas quinzenalmente em nossas redes sociais.<\/span><\/li>\n<li>Participando do nosso Desafio Virtual em parceria com a Chelso Sports! Voc\u00ea corre Quando e Onde quiser, conquista esse kit incr\u00edvel e ainda ajuda o projeto! Para maiores informa\u00e7\u00f5es, clique na imagem abaixo!<\/li>\n<\/ul>\n<figure id=\"attachment_7690\" aria-describedby=\"caption-attachment-7690\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.chelso.com.br\/site\/provas\/corrida-virtual-pernas-caipiras\/\"><img decoding=\"async\" class=\"size-full wp-image-7690\" src=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/03\/Banner-Rotativo-2-3.jpg\" alt=\"pernas caipiras\" width=\"1920\" height=\"800\" srcset=\"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/03\/Banner-Rotativo-2-3.jpg 1920w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/03\/Banner-Rotativo-2-3-300x125.jpg 300w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/03\/Banner-Rotativo-2-3-1024x427.jpg 1024w, https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2021\/03\/Banner-Rotativo-2-3-1536x640.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><figcaption id=\"caption-attachment-7690\" class=\"wp-caption-text\">Quer saber mais? Clique na imagem!!<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">E se voc\u00ea n\u00e3o puder colaborar financeiramente, tudo bem, toda a ajuda ser\u00e1 bem-vinda. Um projeto social \u00e9 feito por pessoas diferentes, mas com um prop\u00f3sito: ser um agente da inclus\u00e3o social. Entre para nosso time de divulgadores do projeto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lembre-se que toda a ajuda ser\u00e1 muito bem-vinda!! Esperamos voc\u00ea!!<\/span><\/p>\n<blockquote><p><i><span style=\"font-weight: 400;\">\u201cSomos todos anjos de uma asa s\u00f3, e s\u00f3 podemos voar quando nos abra\u00e7amos uns as outros\u201d<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">(Luciano Crescenzo)<\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[30],"tags":[136,137,169],"class_list":["post-7689","post","type-post","status-publish","format-standard","category-noticias","tag-acessibilidade","tag-pernas-caipiras","tag-projeto-social"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Pernas Caipiras\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports\" \/>\n\t\t<meta property=\"og:description\" content=\"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-03-19T19:02:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-03-19T19:06:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#blogposting\",\"name\":\"Voc\\u00ea j\\u00e1 pensou em ser um Guia na Corrida? Conhe\\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports\",\"headline\":\"Voc\\u00ea j\\u00e1 pensou em ser um Guia na Corrida? Conhe\\u00e7a o projeto Pernas Caipiras\",\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/pernascaipiras\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PERNAS.jpg\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#articleImage\"},\"datePublished\":\"2021-03-19T16:02:09-03:00\",\"dateModified\":\"2021-03-19T16:06:42-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias, acessibilidade, pernas caipiras, projeto social\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias\",\"item\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#listItem\",\"name\":\"Voc\\u00ea j\\u00e1 pensou em ser um Guia na Corrida? Conhe\\u00e7a o projeto Pernas Caipiras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#listItem\",\"position\":3,\"name\":\"Voc\\u00ea j\\u00e1 pensou em ser um Guia na Corrida? Conhe\\u00e7a o projeto Pernas Caipiras\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/category\\\/noticias\\\/#listItem\",\"name\":\"Not\\u00edcias\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/pernascaipiras\\\/#author\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/pernascaipiras\\\/\",\"name\":\"Pernas Caipiras\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6961c701f3f3e8ef1308821fe6b5374988ee2026b7eb61701370d19bbd38762?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Pernas Caipiras\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#webpage\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/\",\"name\":\"Voc\\u00ea j\\u00e1 pensou em ser um Guia na Corrida? Conhe\\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports\",\"description\":\"O que significa a palavra VOLUNTARIADO? Segundo o dicion\\u00e1rio o termo destina-se a quem est\\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\\u00e7\\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\\u00e1rio como o tempo doado para ajuda\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/pernascaipiras\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/author\\\/pernascaipiras\\\/#author\"},\"datePublished\":\"2021-03-19T16:02:09-03:00\",\"dateModified\":\"2021-03-19T16:06:42-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/\",\"name\":\"Portal Chelso Sports\",\"description\":\"Conte\\u00fado especializado em corrida de rua e triathlon\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/chelso.com.br\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports","description":"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda","canonical_url":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#blogposting","name":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports","headline":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras","author":{"@id":"https:\/\/chelso.com.br\/site\/author\/pernascaipiras\/#author"},"publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/chelso.com.br\/site\/wp-content\/uploads\/2020\/11\/PERNAS.jpg","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#articleImage"},"datePublished":"2021-03-19T16:02:09-03:00","dateModified":"2021-03-19T16:06:42-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#webpage"},"isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#webpage"},"articleSection":"Not\u00edcias, acessibilidade, pernas caipiras, projeto social"},{"@type":"BreadcrumbList","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","position":1,"name":"Home","item":"https:\/\/chelso.com.br\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","name":"Not\u00edcias"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","position":2,"name":"Not\u00edcias","item":"https:\/\/chelso.com.br\/site\/category\/noticias\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#listItem","name":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#listItem","position":3,"name":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras","previousItem":{"@type":"ListItem","@id":"https:\/\/chelso.com.br\/site\/category\/noticias\/#listItem","name":"Not\u00edcias"}}]},{"@type":"Organization","@id":"https:\/\/chelso.com.br\/site\/#organization","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","url":"https:\/\/chelso.com.br\/site\/"},{"@type":"Person","@id":"https:\/\/chelso.com.br\/site\/author\/pernascaipiras\/#author","url":"https:\/\/chelso.com.br\/site\/author\/pernascaipiras\/","name":"Pernas Caipiras","image":{"@type":"ImageObject","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d6961c701f3f3e8ef1308821fe6b5374988ee2026b7eb61701370d19bbd38762?s=96&d=mm&r=g","width":96,"height":96,"caption":"Pernas Caipiras"}},{"@type":"WebPage","@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#webpage","url":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/","name":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports","description":"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/chelso.com.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/#breadcrumblist"},"author":{"@id":"https:\/\/chelso.com.br\/site\/author\/pernascaipiras\/#author"},"creator":{"@id":"https:\/\/chelso.com.br\/site\/author\/pernascaipiras\/#author"},"datePublished":"2021-03-19T16:02:09-03:00","dateModified":"2021-03-19T16:06:42-03:00"},{"@type":"WebSite","@id":"https:\/\/chelso.com.br\/site\/#website","url":"https:\/\/chelso.com.br\/site\/","name":"Portal Chelso Sports","description":"Conte\u00fado especializado em corrida de rua e triathlon","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/chelso.com.br\/site\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Portal Chelso Sports - Conte\u00fado especializado em corrida de rua e triathlon","og:type":"article","og:title":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports","og:description":"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda","og:url":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/","article:published_time":"2021-03-19T19:02:09+00:00","article:modified_time":"2021-03-19T19:06:42+00:00","twitter:card":"summary_large_image","twitter:title":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras - Portal Chelso Sports","twitter:description":"O que significa a palavra VOLUNTARIADO? Segundo o dicion\u00e1rio o termo destina-se a quem est\u00e1 disposto a se dedicar a algo ou alguma coisa sem ter a obriga\u00e7\u00e3o de o fazer ou de lucro, ou seja, motivado por vontade pr\u00f3pria. Existem outras possibilidades de se definir o trabalho volunt\u00e1rio como o tempo doado para ajuda"},"aioseo_meta_data":{"post_id":"7689","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-06 01:00:55","updated":"2025-07-02 18:13:53","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chelso.com.br\/site\/category\/noticias\/\" title=\"Not\u00edcias\">Not\u00edcias<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVoc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chelso.com.br\/site"},{"label":"Not\u00edcias","link":"https:\/\/chelso.com.br\/site\/category\/noticias\/"},{"label":"Voc\u00ea j\u00e1 pensou em ser um Guia na Corrida? Conhe\u00e7a o projeto Pernas Caipiras","link":"https:\/\/chelso.com.br\/site\/voce-ja-pensou-em-ser-um-guia-na-corrida-pernas-caipiras\/"}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/7689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/comments?post=7689"}],"version-history":[{"count":1,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/7689\/revisions"}],"predecessor-version":[{"id":7691,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/posts\/7689\/revisions\/7691"}],"wp:attachment":[{"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/media?parent=7689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/categories?post=7689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chelso.com.br\/site\/wp-json\/wp\/v2\/tags?post=7689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}